{"id":11807,"date":"2026-02-19T08:05:22","date_gmt":"2026-02-19T07:05:22","guid":{"rendered":"https:\/\/theboardbarcelona.com\/?p=11807"},"modified":"2026-05-06T14:14:24","modified_gmt":"2026-05-06T12:14:24","slug":"womens-day-sant-jordi-barcelona-2026","status":"publish","type":"post","link":"https:\/\/theboardbarcelona.com\/es\/womens-day-sant-jordi-barcelona-2026\/","title":{"rendered":"Descubre nuestros productos tem\u00e1ticos y celebraciones especiales para el D\u00eda de la Mujer, Employee Appreciation Day, D\u00eda Internacional de la Felicidad, D\u00eda Internacional del Queso y Sant Jordi 2026 en Barcelona."},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Sin querer sonar demasiado \u201ccheesy\u201d, se acercan fechas importantes y quer\u00edamos recordarte que puedes contar con nosotros.\u00a0Con nuestros nuevos\u00a0productos especiales para fechas se\u00f1aladas y celebraciones, nuestras propuestas van mucho m\u00e1s all\u00e1 del queso y de los grandes formatos.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-left\"><span style=\"text-decoration: underline;\">Te traemos 4 fechas clave\u00a0para generar impacto interno:<\/span><\/h3>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">El <strong>6 de marzo celebramos el Employee Appreciation Day, <\/strong>una ocasi\u00f3n perfecta para agradecer el compromiso de tu equipo con nuestros Plum Cakes o Cheesecake &amp; Brownie Bites. Un detalle sencillo, elegante y muy f\u00e1cil de organizar.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">El <strong>8 de marzo, D\u00eda Internacional de la Mujer, ofrecemos <\/strong><i>macarons morados\u00a0<\/i>disponibles en estuches de 2 o 3 unidades, o presentados sobre nuestras tablas. Tambi\u00e9n podemos personalizarlos con vuestro logo para que encajen perfectamente con vuestra comunicaci\u00f3n interna o identidad de marca.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">El <strong>20 de marzo es el D\u00eda Internacional de la Felicidad.<\/strong> El dinero no compra la felicidad\u2026 pero s\u00ed nuestras tablas de fruta fresca, y es casi lo mismo. Una propuesta colorida, saludable y alegre para sorprender a tu equipo.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">El <strong>27 de marzo, D\u00eda Internacional del Queso<\/strong>, cel\u00e9bralo con nuestra Tabla de Quesos \u00danica. No hace falta decir m\u00e1s.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Y, por supuesto, no nos olvidamos de <strong>Sant Jordi el 23 de abril. <\/strong>Tendremos <i>galletas, cupcakes\u00a0<\/i>y otros productos tem\u00e1ticos disponibles. Esa semana solemos estar casi completos, as\u00ed que te recomendamos hacer tu pedido antes de que sea demasiado tarde.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-black-color has-text-color has-link-color wp-elements-2f720907f7565ff903aa443b242ef6f4\">\u00bfListo para empezar? Rellena el formulario a continuaci\u00f3n y un miembro del equipo de The Board Barcelona\u00ae se pondr\u00e1 en contacto contigo lo antes posible. <\/h2>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-orange-color has-text-color has-link-color wp-elements-e486d12cb79de4085bf79ba25f7bfb98 wp-block-paragraph\"><strong>Haremos que el proceso de pedido sea sencillo y f\u00e1cil \u00a1para que no tengas que preocuparte por nada!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"868\" data-id=\"11808\" src=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Womens-Day-Macarons-2026.jpeg\" alt=\"\" class=\"wp-image-11808\" srcset=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Womens-Day-Macarons-2026.jpeg 771w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Womens-Day-Macarons-2026-266x300.jpeg 266w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Womens-Day-Macarons-2026-768x865.jpeg 768w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Womens-Day-Macarons-2026-11x12.jpeg 11w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"11810\" src=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/MACARONSTHEBOARDBARCELONA-768x1024.jpg\" alt=\"\" class=\"wp-image-11810\" srcset=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/MACARONSTHEBOARDBARCELONA-768x1024.jpg 768w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/MACARONSTHEBOARDBARCELONA-225x300.jpg 225w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/MACARONSTHEBOARDBARCELONA-1152x1536.jpg 1152w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/MACARONSTHEBOARDBARCELONA-1536x2048.jpg 1536w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/MACARONSTHEBOARDBARCELONA-9x12.jpg 9w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/MACARONSTHEBOARDBARCELONA-800x1067.jpg 800w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/MACARONSTHEBOARDBARCELONA.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"777\" height=\"1024\" data-id=\"11811\" src=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBBRoseDecoratedCupcake2026-777x1024.jpeg\" alt=\"\" class=\"wp-image-11811\" srcset=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBBRoseDecoratedCupcake2026-777x1024.jpeg 777w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBBRoseDecoratedCupcake2026-228x300.jpeg 228w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBBRoseDecoratedCupcake2026-768x1012.jpeg 768w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBBRoseDecoratedCupcake2026-9x12.jpeg 9w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBBRoseDecoratedCupcake2026-800x1054.jpeg 800w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBBRoseDecoratedCupcake2026.jpeg 981w\" sizes=\"auto, (max-width: 777px) 100vw, 777px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"11812\" src=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Rose-Themed-Sugar-Butter-Cookies-683x1024.png\" alt=\"\" class=\"wp-image-11812\" srcset=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Rose-Themed-Sugar-Butter-Cookies-683x1024.png 683w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Rose-Themed-Sugar-Butter-Cookies-200x300.png 200w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Rose-Themed-Sugar-Butter-Cookies-768x1152.png 768w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Rose-Themed-Sugar-Butter-Cookies-8x12.png 8w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Rose-Themed-Sugar-Butter-Cookies-800x1200.png 800w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Rose-Themed-Sugar-Butter-Cookies.png 1024w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"11382\" src=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/11\/TBBCheeseOnlyBoard2-768x1024.jpeg\" alt=\"\" class=\"wp-image-11382\" srcset=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/11\/TBBCheeseOnlyBoard2-768x1024.jpeg 768w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/11\/TBBCheeseOnlyBoard2-225x300.jpeg 225w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/11\/TBBCheeseOnlyBoard2-1152x1536.jpeg 1152w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/11\/TBBCheeseOnlyBoard2-9x12.jpeg 9w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/11\/TBBCheeseOnlyBoard2-800x1067.jpeg 800w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/11\/TBBCheeseOnlyBoard2.jpeg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"11852\" src=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Custom-Cookie-Brownie-Board-2026-768x1024.jpeg\" alt=\"\" class=\"wp-image-11852\" srcset=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Custom-Cookie-Brownie-Board-2026-768x1024.jpeg 768w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Custom-Cookie-Brownie-Board-2026-225x300.jpeg 225w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Custom-Cookie-Brownie-Board-2026-1152x1536.jpeg 1152w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Custom-Cookie-Brownie-Board-2026-9x12.jpeg 9w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Custom-Cookie-Brownie-Board-2026-800x1067.jpeg 800w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2026\/02\/TBB-Custom-Cookie-Brownie-Board-2026.jpeg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5636\" src=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2024\/06\/TheBoardBarcelona-Fresh-Fruit-Board-768x1024.jpg\" alt=\"TheBoardBarcelona Fresh Fruit Board\" class=\"wp-image-5636\" srcset=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2024\/06\/TheBoardBarcelona-Fresh-Fruit-Board-768x1025.jpg 768w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2024\/06\/TheBoardBarcelona-Fresh-Fruit-Board-800x1068.jpg 800w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2024\/06\/TheBoardBarcelona-Fresh-Fruit-Board-225x300.jpg 225w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2024\/06\/TheBoardBarcelona-Fresh-Fruit-Board-1151x1536.jpg 1151w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2024\/06\/TheBoardBarcelona-Fresh-Fruit-Board-9x12.jpg 9w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2024\/06\/TheBoardBarcelona-Fresh-Fruit-Board.jpg 1049w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"11052\" src=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/10\/TBB-Brownie-Cheesecake-Board-Standard-2-768x1024.jpeg\" alt=\"\" class=\"wp-image-11052\" srcset=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/10\/TBB-Brownie-Cheesecake-Board-Standard-2-768x1024.jpeg 768w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/10\/TBB-Brownie-Cheesecake-Board-Standard-2-225x300.jpeg 225w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/10\/TBB-Brownie-Cheesecake-Board-Standard-2-1152x1536.jpeg 1152w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/10\/TBB-Brownie-Cheesecake-Board-Standard-2-9x12.jpeg 9w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/10\/TBB-Brownie-Cheesecake-Board-Standard-2-800x1067.jpeg 800w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/10\/TBB-Brownie-Cheesecake-Board-Standard-2.jpeg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"6830\" src=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/01\/TBBStandardBrownieBoard2-768x1024.jpg\" alt=\"\" class=\"wp-image-6830\" srcset=\"https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/01\/TBBStandardBrownieBoard2-768x1024.jpg 768w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/01\/TBBStandardBrownieBoard2-800x1067.jpg 800w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/01\/TBBStandardBrownieBoard2-225x300.jpg 225w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/01\/TBBStandardBrownieBoard2-1152x1536.jpg 1152w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/01\/TBBStandardBrownieBoard2-9x12.jpg 9w, https:\/\/theboardbarcelona.com\/wp-content\/uploads\/2025\/01\/TBBStandardBrownieBoard2.jpg 1050w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<p class=\"wp-block-paragraph\"><em>This form has been deleted.<\/em><\/p>\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un saludo,<br>Jenn &amp; The Board Barcelona Team<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Not to sound \u201ccheesy,\u201d but there are several important dates just around the corner, and we wanted to remind you that we\u2019re here for you. With our new seasonal and celebration-focused products, our proposals now go far beyond cheese and large-format boards Here are four key upcoming dates that we can help you with: On [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_title":"","rank_math_description":"","rank_math_focus_keyword":"","footnotes":""},"categories":[1],"tags":[158,156,160],"class_list":["post-11807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-corporate2026","tag-santjordi2026","tag-santjordibarcelona2026"],"_links":{"self":[{"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/posts\/11807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/comments?post=11807"}],"version-history":[{"count":5,"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/posts\/11807\/revisions"}],"predecessor-version":[{"id":11854,"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/posts\/11807\/revisions\/11854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/media\/11812"}],"wp:attachment":[{"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/media?parent=11807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/categories?post=11807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theboardbarcelona.com\/es\/wp-json\/wp\/v2\/tags?post=11807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}